﻿{"id":42,"date":"2023-04-03T20:55:37","date_gmt":"2023-04-03T18:55:37","guid":{"rendered":"https:\/\/istitutobuenosaires.esteri.it\/?page_id=42"},"modified":"2026-01-08T14:57:11","modified_gmt":"2026-01-08T13:57:11","slug":"i-corsi-di-lingua","status":"publish","type":"page","link":"https:\/\/iiczurigo.esteri.it\/it\/lingua-e-cultura\/i-corsi-di-lingua\/","title":{"rendered":"I corsi di lingua"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-156 img-fluid\" src=\"https:\/\/iiczurigo.esteri.it\/wp-content\/uploads\/2023\/10\/sito_farnesina_course-300x110.jpg\" alt=\"\" width=\"801\" height=\"294\" srcset=\"https:\/\/iiczurigo.esteri.it\/wp-content\/uploads\/2023\/10\/sito_farnesina_course-300x110.jpg 300w, https:\/\/iiczurigo.esteri.it\/wp-content\/uploads\/2023\/10\/sito_farnesina_course-1024x375.jpg 1024w, https:\/\/iiczurigo.esteri.it\/wp-content\/uploads\/2023\/10\/sito_farnesina_course-768x282.jpg 768w, https:\/\/iiczurigo.esteri.it\/wp-content\/uploads\/2023\/10\/sito_farnesina_course.jpg 1920w\" sizes=\"auto, (max-width: 801px) 100vw, 801px\" \/><\/p>\n<p style=\"text-align: justify;\">L\u2019italiano \u00e8 una delle lingue fondamentali della Svizzera e dell\u2019Unione Europea: pi\u00f9 di un milione di persone parlano italiano ogni giorno nella Confederazione, l\u2019italiano \u00e8 una lingua richiesta in molti ambiti dell\u2019amministrazione e dell\u2019economia svizzere, l\u2019italiano viaggia ogni giorno attraverso le Alpi, componente fondamentale di uno scambio di commercio e di cultura con pochi paralleli nel continente. L\u2019italiano \u00e8 la lingua del patrimonio artistico, della musica, della storia: ma anche dell\u2019industria, dello stile di vita, del cibo. L\u2019italiano \u00e8 una delle lingue di Zurigo. Conoscere l\u2019italiano migliora le tue possibilit\u00e0 e ti rende, in sostanza, una persona migliore.<\/p>\n<p style=\"text-align: justify;\">A Zurigo l&#8217;offerta di corsi di italiano \u00e8 vastissima, perch\u00e9 studiare l&#8217;italiano proprio con l&#8217;<strong>Istituto Italiano di Cultura di Zurigo<\/strong>\u00a0e lo\u00a0<a href=\"http:\/\/liceo-vermigli.com\/lezioni-di-italiano\/\"><strong>Sprachzentrum ArteLingua<\/strong><\/a>?<\/p>\n<p style=\"text-align: justify;\">L&#8217;Istituto Italiano di Cultura \u00e8 l\u2019Ufficio della Stato italiano il cui compito \u00e8 la promozione della lingua e della cultura italiane all&#8217;estero. Studiare l\u2019italiano con noi vuol dire apprenderlo grazie ad una vasta e rinnovata offerta di corsi, articolata in base ai livelli di competenza previsti dal\u00a0<strong>Quadro Comune Europeo di Riferimento per le Lingue<\/strong>;<\/p>\n<p style=\"text-align: justify;\">Le lezioni sono impartite da docenti madrelingua professionalmente qualificati e specializzati nella somministrazione di corsi in presenza e online. I gruppi offrono un clima ideale per l&#8217;apprendimento. Offriamo un ambiente dinamico e culturalmente stimolante in cui sviluppare autonomia nelle competenze linguistiche mirate all&#8217;apprendimento dell&#8217;italiano autentico e contemporaneo;<\/p>\n<p style=\"text-align: justify;\">Offriamo la possibilit\u00e0 di frequentare corsi di italiano in Italia a prezzi agevolati presso scuole estive di lingua.<\/p>\n<p style=\"text-align: justify;\">Forniamo informazioni e mettiamo a disposizione inviti relativi agli eventi culturali organizzati dall&#8217;Istituto e da altre istituzioni culturali zurighesi.<\/p>\n<p style=\"text-align: justify;\">Offriamo la possibilit\u00e0 di conseguire la\u00a0<strong>Certificazione di Italiano come Lingua Straniera (CILS)<\/strong>\u00a0gestita dall&#8217;Universit\u00e0 per Stranieri di Siena e di sostenere un esame ufficiale nella sede del Sprachzentrum ArteLingua.<\/p>\n<p style=\"text-align: justify;\"><strong>LUOGO DEL CORSO<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Liceo+Vermigli\/@47.3939719,8.4879479,15z\/data=!4m12!1m6!3m5!1s0x0:0xa4d2391d0529d7df!2sLiceo+Vermigli!8m2!3d47.3939719!4d8.4879479!3m4!1s0x0:0xa4d2391d0529d7df!8m2!3d47.3939719!4d8.4879479\">Sprachzentrum Vermigli-ArteLingua, Herostrasse 7, 8048 Z\u00fcrich<\/a><\/p>\n<p style=\"text-align: justify;\"><em>Mezzi pubblici:<\/em><br \/>\nS-Bahn o tram no. 4 fino alla fermata \u00abBahnhof Altstetten\u00bb, a piedi 2 minuti<\/p>\n<p data-start=\"74\" data-end=\"93\"><strong data-start=\"74\" data-end=\"93\">CORSI 2026<\/strong><\/p>\n<p data-start=\"95\" data-end=\"301\">Il calendario delle lezioni, cos\u00ec come i costi, verranno comunicati direttamente agli studenti e alle studentesse dallo <strong data-start=\"215\" data-end=\"252\">Sprachzentrum Vermigli\u2013ArteLingua<\/strong>. Per maggiori informazioni: Tel. <strong data-start=\"283\" data-end=\"300\">044 305 31 92.<\/strong><\/p>\n<p data-start=\"303\" data-end=\"465\">La <strong data-start=\"306\" data-end=\"320\">Sessione I<\/strong> si svolger\u00e0 tra settembre e dicembre 2025.<br data-start=\"363\" data-end=\"366\" \/>La <strong data-start=\"369\" data-end=\"384\">Sessione II<\/strong> \u00e8 prevista da febbraio a luglio 2026.<br data-start=\"422\" data-end=\"425\" \/>Le lezioni si terranno in orario serale.<\/p>\n<p data-start=\"467\" data-end=\"521\">\n<p><span style=\"color: #339966;\"><strong>NUOVO: CORSO D\u2019ITALIANO A2 <\/strong><\/span><br \/>\n<u>Ogni venerd\u00ec a partire dal 16 gennaio 2026, ore 16:30-18:00<\/u><br \/>\nScopri il Corso di lingua italiana \u2013 Livello A2, organizzato da ArteLingua in collaborazione con l\u2019Istituto Italiano di Cultura: un percorso coinvolgente per migliorare la conversazione, ampliare il vocabolario e approfondire la grammatica italiana. Il corso inizia venerd\u00ec 16 gennaio 2026 e comprende 20 lezioni da 90 minuti ciascuna, al costo di CHF 600 (libro incluso). \u00c8 ideale per chi ha gi\u00e0 una base di italiano e desidera comunicare con pi\u00f9 sicurezza nella vita quotidiana e sociale. Posti limitati: iscriviti ora e continua il tuo percorso in italiano!<br \/>\n<a href=\"https:\/\/iiczurigo.esteri.it\/wp-content\/uploads\/2026\/01\/Corso-di-Italiano-A2p.pdf\"><span style=\"text-decoration: underline;\">Vai alla locandina<\/span><\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>Livelli: MAGGIOR PARTE DEI LIVELLI<\/strong><\/p>\n<p style=\"text-align: justify;\">I nostri corsi di italiano soddisfano ogni esigenza al fine di ottenere un diploma riconosciuto a livello internazionale o solo per promuovere la lingua italiana; infatti, ArteLingua offre i seguenti servizi e prepara ai seguenti esami:<\/p>\n<p style=\"text-align: justify;\">\u2022 Livelli A1-C2<\/p>\n<p style=\"text-align: justify;\">\u2022 Corsi per specifiche esigenze, anche presso Aziende<\/p>\n<p style=\"text-align: justify;\">\u2022 Lezioni private \/ individuali o di gruppo eventualmente<\/p>\n<p style=\"text-align: justify;\">\u2022 Lezioni di Recupero per studenti<\/p>\n<p style=\"text-align: justify;\">\u2022 Incontri di Conversazione eventualmente su temi specifici<\/p>\n<p style=\"text-align: justify;\">\u2022 Organizzazione di corsi ad hoc, su richiesta<\/p>\n<p style=\"text-align: justify;\">\u2022 Certificazioni CILS<\/p>\n<p style=\"text-align: justify;\">\u2022 Corsi di preparazione CILS<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>MODULO D\u2019ISCRIZIONE<\/strong><\/p>\n<p style=\"text-align: justify;\">L\u2019iscrizione \u00e8 molto semplice: compila il seguente formulario cliccando <a href=\"https:\/\/forms.gle\/uS7uxwJgWeNXDkNa9\"><strong>&gt; qui.<\/strong>\u00a0<\/a>Verrai ricontattato\/ricontattata il pi\u00f9 presto possibile con maggiori informazioni.<\/p>\n<p style=\"text-align: justify;\"><strong><br \/>\nCONDIZIONI<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\">Iscrizioni<br \/>\n<\/span>I corsi inizieranno solo se sar\u00e0 raggiunto un numero minimo di iscrizioni (7 studenti per corso &#8211; numero massimo: 12 studenti).\u00a0<strong>In circostanze eccezionali possono essere attivati corsi anche con un numero inferiore di studenti, nel qual caso il numero di ore del corso verr\u00e0 ridotto (ad esempio 5 studenti: 20 ore, 4 studenti: 18 ore).<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\">Pagamento<br \/>\n<\/span>Le iscrizioni sono aperte tutto l\u2019anno. Tuttavia, raccomandiamo caldamente di iscriversi al pi\u00f9 presto, dato che alcuni corsi si riempiono molto velocemente.<\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\">Rimborsi<\/span><br \/>\nLe tasse d&#8217;iscrizione verranno rimborsate al 100% se il corso viene cancellato a causa di un numero insufficiente di iscrizioni.\u00a0<strong>Una volta che il corso \u00e8 iniziato le tasse non possono essere rimborsate o trasferite ad un altro corso. L&#8217;Istituto\/lo Sprachzentrum ArteLingua non possono essere ritenuti responsabile di eventuali cambiamenti nelle circostanze personali dello studente\/della studentessa.<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\">Covid<\/span><br \/>\nLa modalit\u00e0 di erogazione dei corsi dipender\u00e0 dalla situazione dei contagi di Covid e dalle preferenze degli studenti. Pertanto i corsi potrebbero essere offerti IN PRESENZA oppure ONLINE.<\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\">Lezione di prova \u201cSchnupperlektion\u201d<br \/>\n<\/span>Non riesci ancora a deciderti per un corso? Vi offriamo la possibilit\u00e0 di partecipare gratuitamente a una doppia lezione (90 minuti) come studente\/studentessa ospite!<\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\">Ri-pianificazione delle lezioni<br \/>\n<\/span>In circostanze eccezionali &#8211; di solito legate a festivit\u00e0 e\/o ferie \u2013\u00a0<strong>l&#8217;Istituto\/ArteLinuga si riserva il diritto di modificare il giorno e l&#8217;orario di alcune lezioni sulla base delle esigenze degli studenti e degli insegnanti.<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\">Test d\u2019ingresso<br \/>\n<\/span>Con l\u2019eccezione dei\u00a0<em>complete beginners<\/em>, gli studenti che hanno gi\u00e0 studiato l\u2019italiano e che desiderano iscriversi ad un livello superiore dovranno sottoporsi ad un breve test d\u2019ingresso per determinare quale corso sia pi\u00f9 adatto al loro livello. I test verranno erogati\/inviati ai potenziali studenti dietro richiesta.<\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\">Tessera associativa<br \/>\n<\/span>Gli studenti iscritti ai corsi di Italiano organizzati dall\u2019Istituto ottengono l\u2019accesso alla biblioteca digitale dell\u2019Istituto Italiano di Cultura di Zurigo per la durata del corso. Tale accesso consente loro di\u00a0<strong>prendere in prestito GRATUITAMENTE libri digitali dalla nostra biblioteca.<\/strong>\u00a0<strong>Se lo studente\/studentessa desidera ottenere una tessera annuale che gli\/le permetter\u00e0 anche di accedere a tutti gli altri vantaggi dei soci dell\u2019Istituto, avr\u00e0 diritto ad uno sconto del 50% sulla normale quota associativa.<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\">Borse di studio<br \/>\n<\/span>L\u2019Istituto Italiano di Cultura di Zurigo offre ai suoi studenti delle borse di studio per frequentare corsi di lingua italiana in Italia. Per saperne di pi\u00f9 cliccate\u00a0<a href=\"https:\/\/iiczurigo.esteri.it\/it\/lingua-e-cultura\/borse-di-studio\/\"><strong>&gt; qui.<\/strong><\/a><\/p>\n<p style=\"text-align: justify;\">Per qualsiasi altra informazione contattare:<\/p>\n<p style=\"text-align: justify;\"><strong>Sprachzentrum Vermigli-ArteLingua<\/strong><br \/>\nHerostr. 7<br \/>\nZ\u00fcrich<br \/>\nTel. 044 305 31 92<br \/>\nE-Mail:\u00a0<a href=\"info.artelingua@liceo-vermigli.ch\">info.artelingua@liceo-vermigli.ch<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.liceo-vermigli.ch\/artelingua-corsi-italiano-liceo-vermigli-zurigo.php\">Sito web<\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">oppure<\/p>\n<p style=\"text-align: justify;\"><strong>Italienisches Kulturinstitut Z\u00fcrich<\/strong><br \/>\nT\u00f6distr. 65<br \/>\nZ\u00fcrich<br \/>\nTel. 044 202 48 46<br \/>\nE-Mail:\u00a0<a href=\"mailto:iiczurigo@esteri.it\">iiczurigo@esteri.it<\/a><br \/>\n<a href=\"https:\/\/iiczurigo.esteri.it\/it\/\"><span style=\"text-decoration: underline;\">Sito web<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"&nbsp; L\u2019italiano \u00e8 una delle lingue fondamentali della Svizzera e dell\u2019Unione Europea: pi\u00f9 di un milione di persone parlano italiano ogni giorno nella Confederazione, l\u2019italiano \u00e8 una lingua richiesta in molti ambiti dell\u2019amministrazione e dell\u2019economia svizzere, l\u2019italiano viaggia ogni giorno attraverso le Alpi, componente fondamentale di uno scambio di commercio e di cultura con pochi [&hellip;]","protected":false},"author":1,"featured_media":0,"parent":16,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-42","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/iiczurigo.esteri.it\/it\/wp-json\/wp\/v2\/pages\/42","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iiczurigo.esteri.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/iiczurigo.esteri.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/iiczurigo.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/iiczurigo.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=42"}],"version-history":[{"count":6,"href":"https:\/\/iiczurigo.esteri.it\/it\/wp-json\/wp\/v2\/pages\/42\/revisions"}],"predecessor-version":[{"id":18468,"href":"https:\/\/iiczurigo.esteri.it\/it\/wp-json\/wp\/v2\/pages\/42\/revisions\/18468"}],"up":[{"embeddable":true,"href":"https:\/\/iiczurigo.esteri.it\/it\/wp-json\/wp\/v2\/pages\/16"}],"wp:attachment":[{"href":"https:\/\/iiczurigo.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=42"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}